{"id":456277,"date":"2018-09-19T17:39:53","date_gmt":"2018-09-19T16:39:53","guid":{"rendered":"https:\/\/www.classiccar-auctions.com\/?page_id=456277"},"modified":"2023-01-06T10:12:55","modified_gmt":"2023-01-06T09:12:55","slug":"auction-67957","status":"publish","type":"page","link":"https:\/\/archive.classiccar-auctions.com\/en\/auction-67957\/","title":{"rendered":"Auction 67957"},"content":{"rendered":"<div id=\"fws_6a0451fabf775\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 150px; padding-bottom: 150px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image\"  style=\"background-image: url(https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/header-uithoorn-december2022-1.jpg); background-position: center center; background-repeat: no-repeat; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background:linear-gradient(0deg, rgb(0,0,0) 10%, rgba(20,20,20,0.512) 90%);\"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col centered-text padding-1-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2 style=\"text-align: center;\">New Year&#039;s auction Classic, Sports Cars &amp; Youngtimers in Uithoorn<\/h2>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"nectar-next-section-wrap minimal-arrow alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit\"  data-align=\"center\" data-custom-color=\"true\">\n    <a href=\"#\" class=\"nectar-next-section skip-hash\">\n      <span class=\"screen-reader-text\">Navigate to the next section<\/span>\n      <svg class=\"next-arrow\" width=\"40px\" height=\"68px\" viewbox=\"0 0 40 50\" xml:space=\"preserve\">\n      <path stroke=\"#ffffff\" stroke-width=\"2\" fill=\"none\" d=\"M 20 0 L 20 51\"><\/path>\n      <polyline stroke=\"#ffffff\" stroke-width=\"2\" fill=\"none\" points=\"12, 44 20, 52 28, 44\"><\/polyline>\n      <\/svg>\n    <\/a>\n  <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a0451fac02e5\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"3%\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: calc(100vw * 0.03); padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3><span class=\"inner\">Auction dates<\/span><\/h3>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><strong>Start auction:<\/strong> Friday, December 16, 2022 at 5:00 PM<br \/>\n<strong>Closure:<\/strong> Wednesday, January 4, 2023 from 8:00 PM<\/p>\n<p><strong>Viewing days:<br \/>\n<\/strong>Friday December 23, 2022 10:00 AM to 4:00 PM<br \/>\nTuesday, January 3, 2023 10:00 a.m. to 4:00 p.m<\/p>\n<p><strong>Location:<\/strong><br \/>\nAnthony Fokkerweg 7<br \/>\n1422 AE Uithoorn<br \/>\nthe Netherlands<\/p>\n<p><strong>Collection day:<br \/>\n<\/strong>Friday, January 13, 2023 from 10:00 AM to 4:00 PM<br \/>\nAnthony Fokkerweg 7<br \/>\n1422 AE Uithoorn<br \/>\nthe Netherlands<\/p>\n<p>As an extra service, we offer to deliver the won car within the Netherlands for \u20ac195 (incl. VAT). If you live abroad, we can arrange transport in consultation at the best possible rate. <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/transportprijzen\/\">More information.<\/a><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3><span class=\"inner\">Additional<\/span>\u00a0<span class=\"inner\">information<\/span><\/h3>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>On behalf of various private and business sellers, Classic Car Auctions organizes this online auction in collaboration with BVA Auctions. You can bid on a car by clicking the \u201cBid\u201d button, after which you will be referred to the auction section of the BVA Auctions website.<\/p>\n<p>It is always possible to enter cars for the next auction. For information about the conditions, please contact us at\u00a0<a href=\"https:\/\/archive.classiccar-auctions.com\/en\/contact\/\">our contact form<\/a>.<\/p>\n<p>Because the cars in the auction are sold without warranty, we advise you to personally inspect the cars on the viewing days. It is also possible to have this done by an expert. If desired, a special appointment can be made for this. Please check your local vehicle registration laws prior to bidding. Neither the seller nor Classic Car Auctions nor BVA Auctions is responsible for the registration of the vehicle in your country.<\/p>\n<p>The lot description on the website is based on the information known to Classic Car Auctions. Classic Car Auctions is not a garage or repair company and does not check whether everything functions properly.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a0451fac09ea\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a0451fac0cae\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 40px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2><span class=\"inner\">Lots<\/span><\/h2>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; width: 60px; height: 1px; margin-bottom: 12.5px;\" data-width=\"60px\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"extra-color-gradient-1\" class=\"divider-small-border\"><\/div><\/div>\n    <div class=\"row blog-recent columns-3\" data-style=\"classic_enhanced\" data-color-scheme=\"light\" data-remove-post-date=\"1\" data-remove-post-author=\"1\" data-remove-post-comment-number=\"1\" data-remove-post-nectar-love=\"1\">\n\n      \n      <div class=\"col span_4 post-458129 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458129 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-z8-2001\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2043-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-z8-2001\/\" ><span class=\"screen-reader-text\">BMW Z8 2001<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW Z8 2001<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-1 | \u20ac 235,000-270,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458129\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458131 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ferrari\" >\n\n        \n            <div class=\"inner-wrap post-458131 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ferrari\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ferrari-mondial-3-2-convertible-1987-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2020-1149-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ferrari-mondial-3-2-convertible-1987-2\/\" ><span class=\"screen-reader-text\">Ferrari Mondial 3.2 Convertible 1987<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ferrari Mondial 3.2 Convertible 1987<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-2 | \u20ac55,000-59,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458131\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458133 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ferrari\" >\n\n        \n            <div class=\"inner-wrap post-458133 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ferrari\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ferrari-f430-spider-f1-2007\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2058-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ferrari-f430-spider-f1-2007\/\" ><span class=\"screen-reader-text\">Ferrari F430 Spider F1 2007<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ferrari F430 Spider F1 2007<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-3 | \u20ac 105,000-115,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458133\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458135 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\" >\n\n        \n            <div class=\"inner-wrap post-458135 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-e-type-series-iii-v12-convertible-1974\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2049-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-e-type-series-iii-v12-convertible-1974\/\" ><span class=\"screen-reader-text\">Jaguar E-Type Series III V12 Convertible 1974<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jaguar E-Type Series III V12 Convertible 1974<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-4 | \u20ac 125,000-139,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458135\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458137 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jensen\" >\n\n        \n            <div class=\"inner-wrap post-458137 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jensen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jensen-interceptor-iii-convertible-1974-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2021-1291-2-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jensen-interceptor-iii-convertible-1974-3\/\" ><span class=\"screen-reader-text\">Jensen Interceptor III Convertible 1974<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jensen Interceptor III Convertible 1974<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-5 | \u20ac 55,000-65,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458137\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458139 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\" >\n\n        \n            <div class=\"inner-wrap post-458139 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-phantom-6-7-v12-2006-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1948-2-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-phantom-6-7-v12-2006-3\/\" ><span class=\"screen-reader-text\">Rolls Royce Phantom 6.7 V12 2006<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Rolls Royce Phantom 6.7 V12 2006<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-6 | \u20ac 87,000-98,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458139\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458141 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ferrari\" >\n\n        \n            <div class=\"inner-wrap post-458141 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ferrari\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ferrari-400i-1985\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2048-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ferrari-400i-1985\/\" ><span class=\"screen-reader-text\">Ferrari 400i 1985<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ferrari 400i 1985<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-7 | \u20ac 58,000-65,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458141\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458143 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458143 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-230-sl-1964\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2089-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-230-sl-1964\/\" ><span class=\"screen-reader-text\">Mercedes Benz 230 SL 1964<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 230 SL 1964<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-8 | \u20ac 65,000-72,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458143\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458145 post type-post status-publish format-standard has-post-thumbnail category-638 tag-lancia\" >\n\n        \n            <div class=\"inner-wrap post-458145 post type-post status-publish format-standard has-post-thumbnail category-638 tag-lancia\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/lancia-delta-hf-integrale-16v-1989\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2061-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/lancia-delta-hf-integrale-16v-1989\/\" ><span class=\"screen-reader-text\">Lancia Delta HF Integrale 16V 1989<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Lancia Delta HF Integrale 16V 1989<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-9 | \u20ac 34,000-39,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458145\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458147 post type-post status-publish format-standard has-post-thumbnail category-638 tag-aston-martin\" >\n\n        \n            <div class=\"inner-wrap post-458147 post type-post status-publish format-standard has-post-thumbnail category-638 tag-aston-martin\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/aston-martin-virage-volante-1997-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2031-1-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/aston-martin-virage-volante-1997-2\/\" ><span class=\"screen-reader-text\">Aston Martin Virage Volante 1997<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Aston Martin Virage Volante 1997<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-10 | \u20ac 87,000-98,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458147\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458149 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458149 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-190-sl-1958-4\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2021-1460-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-190-sl-1958-4\/\" ><span class=\"screen-reader-text\">Mercedes Benz 190 SL 1958<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 190 SL 1958<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-11 | \u20ac 125,000-138,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458149\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458151 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bentley\" >\n\n        \n            <div class=\"inner-wrap post-458151 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bentley\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bentley-continental-gtc-6-0-w12-2008\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2037-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bentley-continental-gtc-6-0-w12-2008\/\" ><span class=\"screen-reader-text\">Bentley Continental GTC 6.0 W12 2008<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Bentley Continental GTC 6.0 W12 2008<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-12 | \u20ac 62,000-68,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458151\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458153 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\" >\n\n        \n            <div class=\"inner-wrap post-458153 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-356-b-1600-1963\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2078-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-356-b-1600-1963\/\" ><span class=\"screen-reader-text\">Porsche 356 B 1600 1963<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Porsche 356 B 1600 1963<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-13 | \u20ac 57,000-65,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458153\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458155 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458155 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-z1-1991-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2044-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-z1-1991-2\/\" ><span class=\"screen-reader-text\">BMW Z1 1991<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW Z1 1991<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-14 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458155\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458157 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458157 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-220-se-1964-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1945-1-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-220-se-1964-3\/\" ><span class=\"screen-reader-text\">Mercedes Benz 220 SE 1964<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 220 SE 1964<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-15 | \u20ac 38,000-44,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458157\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458159 post type-post status-publish format-standard has-post-thumbnail category-638 tag-audi\" >\n\n        \n            <div class=\"inner-wrap post-458159 post type-post status-publish format-standard has-post-thumbnail category-638 tag-audi\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/audi-rs2-h6-porsche-1994-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1941-1-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/audi-rs2-h6-porsche-1994-2\/\" ><span class=\"screen-reader-text\">Audi RS2 H6 Porsche 1994<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Audi RS2 H6 Porsche 1994<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-16 | \u20ac 56,000-61,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458159\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458161 post type-post status-publish format-standard has-post-thumbnail category-638 tag-austin-healey\" >\n\n        \n            <div class=\"inner-wrap post-458161 post type-post status-publish format-standard has-post-thumbnail category-638 tag-austin-healey\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/austin-healey-3000-mk-iii-bj8-phase-ii-1967-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1979-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/austin-healey-3000-mk-iii-bj8-phase-ii-1967-2\/\" ><span class=\"screen-reader-text\">Austin-Healey 3000 Mk III BJ8 Phase II 1967<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Austin-Healey 3000 Mk III BJ8 Phase II 1967<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-17 | \u20ac 74,000-79,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458161\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458163 post type-post status-publish format-standard has-post-thumbnail category-638 tag-excalibur\" >\n\n        \n            <div class=\"inner-wrap post-458163 post type-post status-publish format-standard has-post-thumbnail category-638 tag-excalibur\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/excalibur-phaeton-1979\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2041-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/excalibur-phaeton-1979\/\" ><span class=\"screen-reader-text\">Excalibur Phaeton 1979<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Excalibur Phaeton 1979<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-18 | \u20ac 45,000-53,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458163\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458165 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\" >\n\n        \n            <div class=\"inner-wrap post-458165 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xkr-5-0-v8-supercharged-2013-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1969-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xkr-5-0-v8-supercharged-2013-2\/\" ><span class=\"screen-reader-text\">2013 Jaguar XKR 5.0 V8 Supercharged<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">2013 Jaguar XKR 5.0 V8 Supercharged<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-19 | \u20ac 44,000-49,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458165\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458167 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\" >\n\n        \n            <div class=\"inner-wrap post-458167 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-t1-1966\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2069-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-t1-1966\/\" ><span class=\"screen-reader-text\">Volkswagen T1 1966<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volkswagen T1 1966<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-20 | \u20ac 62,000-69,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458167\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458169 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\" >\n\n        \n            <div class=\"inner-wrap post-458169 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-karmann-ghia-coupe-1973\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2065-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-karmann-ghia-coupe-1973\/\" ><span class=\"screen-reader-text\">Volkswagen Karmann Ghia Coupe 1973<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volkswagen Karmann Ghia Coupe 1973<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-21 | \u20ac 23,500-26,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458169\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458171 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bentley\" >\n\n        \n            <div class=\"inner-wrap post-458171 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bentley\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bentley-arnage-2003\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2038-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bentley-arnage-2003\/\" ><span class=\"screen-reader-text\">Bentley Arnage 2003<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Bentley Arnage 2003<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-22 | \u20ac 35,000-39,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458171\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458173 post type-post status-publish format-standard has-post-thumbnail category-638 tag-talbot\" >\n\n        \n            <div class=\"inner-wrap post-458173 post type-post status-publish format-standard has-post-thumbnail category-638 tag-talbot\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/talbot-k78l-1931-4\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2020-1050-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/talbot-k78l-1931-4\/\" ><span class=\"screen-reader-text\">Talbot K78L 1931<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Talbot K78L 1931<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-23 | \u20ac 29,000-34,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458173\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458175 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mg\" >\n\n        \n            <div class=\"inner-wrap post-458175 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mg\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mg-a-cabriolet-1958\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2083-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mg-a-cabriolet-1958\/\" ><span class=\"screen-reader-text\">MG A Convertible 1958<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">MG A Convertible 1958<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-24 | \u20ac 26,000-29,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458175\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458177 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\" >\n\n        \n            <div class=\"inner-wrap post-458177 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xj12c-5-3-v12-1976-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1890-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xj12c-5-3-v12-1976-2\/\" ><span class=\"screen-reader-text\">Jaguar XJ12C 5.3 V12 1976<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jaguar XJ12C 5.3 V12 1976<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-25 | \u20ac 26,000-28,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458177\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458179 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\" >\n\n        \n            <div class=\"inner-wrap post-458179 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-356-pre-a-convertible-1953-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1750-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-356-pre-a-convertible-1953-3\/\" ><span class=\"screen-reader-text\">Porsche 356 Pre-A Convertible 1953<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Porsche 356 Pre-A Convertible 1953<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-26 | \u20ac 245,000-265,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458179\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458181 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458181 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-tt-1922\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2053-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-tt-1922\/\" ><span class=\"screen-reader-text\">Ford TT 1922<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford TT 1922<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-27 | \u20ac 24,500-28,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458181\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458183 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458183 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-f-250-1970\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1958-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-f-250-1970\/\" ><span class=\"screen-reader-text\">Ford F-250 1970<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford F-250 1970<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-28 | \u20ac 19,500-22,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458183\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458185 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bentley\" >\n\n        \n            <div class=\"inner-wrap post-458185 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bentley\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bentley-brooklands-6-8-1994-6\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2020-877-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bentley-brooklands-6-8-1994-6\/\" ><span class=\"screen-reader-text\">Bentley Brooklands 6.8 1994<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Bentley Brooklands 6.8 1994<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-29 | \u20ac 22,500-25,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458185\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458187 post type-post status-publish format-standard has-post-thumbnail category-638 tag-alfa-romeo\" >\n\n        \n            <div class=\"inner-wrap post-458187 post type-post status-publish format-standard has-post-thumbnail category-638 tag-alfa-romeo\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/alfa-romeo-1750-gtv-1969\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2042-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/alfa-romeo-1750-gtv-1969\/\" ><span class=\"screen-reader-text\">Alfa Romeo 1750 GTV 1969<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Alfa Romeo 1750 GTV 1969<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-30 | \u20ac 55,000-62,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458187\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458189 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458189 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-alpina-b3s-2003-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1984-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-alpina-b3s-2003-3\/\" ><span class=\"screen-reader-text\">BMW Alpina B3S 2003<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW Alpina B3S 2003<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-31 | \u20ac 28,000-32,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458189\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458191 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volvo\" >\n\n        \n            <div class=\"inner-wrap post-458191 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volvo\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volvo-1800-es-automaat-1978\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2067-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volvo-1800-es-automaat-1978\/\" ><span class=\"screen-reader-text\">Volvo 1800 ES Automatic 1978<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volvo 1800 ES Automatic 1978<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-32 | \u20ac 22,000-25,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458191\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458193 post type-post status-publish format-standard has-post-thumbnail category-638 tag-triumph\" >\n\n        \n            <div class=\"inner-wrap post-458193 post type-post status-publish format-standard has-post-thumbnail category-638 tag-triumph\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/triumph-tr6-convertible-1976\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2068-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/triumph-tr6-convertible-1976\/\" ><span class=\"screen-reader-text\">Triumph TR6 Convertible 1976<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Triumph TR6 Convertible 1976<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-33 | \u20ac 23,000-26,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458193\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458195 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458195 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-2000-c-1970\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2102-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-2000-c-1970\/\" ><span class=\"screen-reader-text\">BMW 2000C 1970<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW 2000C 1970<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-34 | \u20ac 24,000-27,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458195\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458197 post type-post status-publish format-standard has-post-thumbnail category-638 tag-citroen\" >\n\n        \n            <div class=\"inner-wrap post-458197 post type-post status-publish format-standard has-post-thumbnail category-638 tag-citroen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/citroen-az-2cv-ribbeleend\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2035-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/citroen-az-2cv-ribbeleend\/\" ><span class=\"screen-reader-text\">Citro\u00ebn AZ 2CV Ribbelend<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Citro\u00ebn AZ 2CV Ribbelend<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-35 | \u20ac 19,500-22,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458197\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458199 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458199 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-explorer-4-0l-v6-xlt-sohc-16v-4wd-2007-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1876-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-explorer-4-0l-v6-xlt-sohc-16v-4wd-2007-3\/\" ><span class=\"screen-reader-text\">Ford Explorer 4.0L V6 XLT SOHC 16V 4WD 2007<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford Explorer 4.0L V6 XLT SOHC 16V 4WD 2007<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-36 | \u20ac15,500-17,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458199\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458201 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458201 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-capri-mk-i-2300gt-xlr-1969-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2017-2-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-capri-mk-i-2300gt-xlr-1969-2\/\" ><span class=\"screen-reader-text\">Ford Capri Mk I 2300GT XLR 1969<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford Capri Mk I 2300GT XLR 1969<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-37 | \u20ac 19,500-23,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458201\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458203 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458203 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-280sl-automatic\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2013-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-280sl-automatic\/\" ><span class=\"screen-reader-text\">Mercedes Benz 280SL Automatic<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 280SL Automatic<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-38 | \u20ac 59,000-67,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458203\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458205 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\" >\n\n        \n            <div class=\"inner-wrap post-458205 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-camargue-1976\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2072-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-camargue-1976\/\" ><span class=\"screen-reader-text\">Rolls Royce Camargue 1976<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Rolls Royce Camargue 1976<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-39 | \u20ac 45,000-52,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458205\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458207 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mg\" >\n\n        \n            <div class=\"inner-wrap post-458207 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mg\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mg-td-1952\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2019-75-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mg-td-1952\/\" ><span class=\"screen-reader-text\">MG TD 1952<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">MG TD 1952<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-40 | \u20ac 23,500-27,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458207\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458209 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\" >\n\n        \n            <div class=\"inner-wrap post-458209 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xjs-v12-1983\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2052-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xjs-v12-1983\/\" ><span class=\"screen-reader-text\">Jaguar XJS V12 1983<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jaguar XJS V12 1983<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-41 | \u20ac 12,500-14,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458209\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458211 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\" >\n\n        \n            <div class=\"inner-wrap post-458211 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-bugster-2000\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2076-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-bugster-2000\/\" ><span class=\"screen-reader-text\">Porsche Bugster 2000<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Porsche Bugster 2000<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-42 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458211\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458213 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458213 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-gl-500-4matic-5-5l-v8-2007\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2087-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-gl-500-4matic-5-5l-v8-2007\/\" ><span class=\"screen-reader-text\">Mercedes Benz GL 500 4MATIC 5.5L V8 2007<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz GL 500 4MATIC 5.5L V8 2007<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-43 | \u20ac 28,000-32,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458213\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458215 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\" >\n\n        \n            <div class=\"inner-wrap post-458215 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-t2b-westfalia-1978\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2107-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-t2b-westfalia-1978\/\" ><span class=\"screen-reader-text\">Volkswagen T2B Westfalia 1978<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volkswagen T2B Westfalia 1978<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-44 | \u20ac 45,000-50,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458215\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458217 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\" >\n\n        \n            <div class=\"inner-wrap post-458217 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-silver-shadow-6-8-saloon-type-ll-1970-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2021-1483-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-silver-shadow-6-8-saloon-type-ll-1970-3\/\" ><span class=\"screen-reader-text\">Rolls-Royce Silver Shadow 6.8 Saloon type ll 1970<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Rolls-Royce Silver Shadow 6.8 Saloon type ll 1970<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-45 | \u20ac 11,500-13,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458217\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458219 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\" >\n\n        \n            <div class=\"inner-wrap post-458219 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-944-turbo-1986-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1965-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-944-turbo-1986-2\/\" ><span class=\"screen-reader-text\">Porsche 944 Turbo 1986<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Porsche 944 Turbo 1986<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-46 | \u20ac 21,500-24,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458219\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458221 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\" >\n\n        \n            <div class=\"inner-wrap post-458221 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-911-3-4-coupe-carrera-996-1997\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2073-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-911-3-4-coupe-carrera-996-1997\/\" ><span class=\"screen-reader-text\">Porsche 911 3.4 Coupe Carrera (996) 1997<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Porsche 911 3.4 Coupe Carrera (996) 1997<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-47 | \u20ac 22,500-26,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458221\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458223 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458223 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-mustang-gt-5-0l-v8-2016\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2094-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-mustang-gt-5-0l-v8-2016\/\" ><span class=\"screen-reader-text\">Ford Mustang GT 5.0L V8 2016<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford Mustang GT 5.0L V8 2016<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-48 | \u20ac 39,000-44,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458223\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458225 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458225 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-635-csi-1985-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1956-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-635-csi-1985-2\/\" ><span class=\"screen-reader-text\">BMW 635 CSi 1985<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW 635 CSi 1985<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-49 | \u20ac 21,500-24,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458225\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458227 post type-post status-publish format-standard has-post-thumbnail category-638 tag-alfa-romeo\" >\n\n        \n            <div class=\"inner-wrap post-458227 post type-post status-publish format-standard has-post-thumbnail category-638 tag-alfa-romeo\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/alfa-romeo-giulia-1300-ti-1967-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1980-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/alfa-romeo-giulia-1300-ti-1967-2\/\" ><span class=\"screen-reader-text\">Alfa Romeo Giulia 1300 Ti 1967<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Alfa Romeo Giulia 1300 Ti 1967<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-50 | \u20ac 14,000-16,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458227\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458229 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\" >\n\n        \n            <div class=\"inner-wrap post-458229 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-t1-1959\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2070-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-t1-1959\/\" ><span class=\"screen-reader-text\">Volkswagen T1 1959<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volkswagen T1 1959<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-51 | \u20ac 44,000-49,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458229\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458231 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458231 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-560-sl-1987-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1917-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-560-sl-1987-3\/\" ><span class=\"screen-reader-text\">Mercedes Benz 560 SL 1987<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 560 SL 1987<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-52 | \u20ac 23,500-27,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458231\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458233 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458233 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-alpina-b10v8s-2002-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1985-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-alpina-b10v8s-2002-2\/\" ><span class=\"screen-reader-text\">BMW Alpina B10V8S 2002<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW Alpina B10V8S 2002<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-53 | \u20ac 40,000-45,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458233\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458235 post type-post status-publish format-standard has-post-thumbnail category-638 tag-maserati\" >\n\n        \n            <div class=\"inner-wrap post-458235 post type-post status-publish format-standard has-post-thumbnail category-638 tag-maserati\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/maserati-quattroporte-4-7-s-2008\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2096-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/maserati-quattroporte-4-7-s-2008\/\" ><span class=\"screen-reader-text\">Maserati Quattroporte 4.7 S 2008<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Maserati Quattroporte 4.7 S 2008<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-54 | \u20ac 29,000-32,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458235\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458237 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458237 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-300-se-rally-1962-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1946-1-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-300-se-rally-1962-3\/\" ><span class=\"screen-reader-text\">Mercedes-Benz 300 SE Rally 1962<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes-Benz 300 SE Rally 1962<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-55 | \u20ac 35,000-39,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458237\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458239 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\" >\n\n        \n            <div class=\"inner-wrap post-458239 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-356-speedster-replica-1973\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2074-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-356-speedster-replica-1973\/\" ><span class=\"screen-reader-text\">Porsche 356 Speedster Replica 1973<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Porsche 356 Speedster Replica 1973<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-56 | \u20ac 39,000-44,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458239\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458241 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen-ruska\" >\n\n        \n            <div class=\"inner-wrap post-458241 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen-ruska\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-ruska-sport-buggy-mk-i-1962-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2018-2-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-ruska-sport-buggy-mk-i-1962-2\/\" ><span class=\"screen-reader-text\">Volkswagen Ruska Sport Buggy Mk I 1962<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volkswagen Ruska Sport Buggy Mk I 1962<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-57 | \u20ac8,700-9,800 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458241\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458243 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458243 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-g55-amg-kompressor-lang-2011\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2101-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-g55-amg-kompressor-lang-2011\/\" ><span class=\"screen-reader-text\">Mercedes-Benz G55 AMG Kompressor Long 2011<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes-Benz G55 AMG Kompressor Long 2011<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-58 | \u20ac 67,000-72,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458243\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458245 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\" >\n\n        \n            <div class=\"inner-wrap post-458245 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-e-type-5-3-v12-22-1971\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2090-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-e-type-5-3-v12-22-1971\/\" ><span class=\"screen-reader-text\">Jaguar E-Type 5.3 V12 2+2 1971<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jaguar E-Type 5.3 V12 2+2 1971<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-59 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458245\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458247 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458247 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-explorer-4-6l-v8-xlt-limited-4wd-2006\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1976-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-explorer-4-6l-v8-xlt-limited-4wd-2006\/\" ><span class=\"screen-reader-text\">Ford Explorer 4.6L V8 XLT Limited 4WD 2006<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford Explorer 4.6L V8 XLT Limited 4WD 2006<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-60 | \u20ac14,500-16,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458247\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458249 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\" >\n\n        \n            <div class=\"inner-wrap post-458249 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-zastava-750-le-abarth-creation-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/A-2020-671-2-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-zastava-750-le-abarth-creation-3\/\" ><span class=\"screen-reader-text\">Fiat Zastava 750 LE (Abarth creation)<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Fiat Zastava 750 LE (Abarth creation)<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-61 | \u20ac6,000-7,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458249\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458251 post type-post status-publish format-standard has-post-thumbnail category-638 tag-daimler\" >\n\n        \n            <div class=\"inner-wrap post-458251 post type-post status-publish format-standard has-post-thumbnail category-638 tag-daimler\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/daimler-century-mk-ii-1957\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2039-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/daimler-century-mk-ii-1957\/\" ><span class=\"screen-reader-text\">Daimler Century Mk II 1957<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Daimler Century Mk II 1957<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-62 | \u20ac15,000-17,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458251\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458253 post type-post status-publish format-standard has-post-thumbnail category-638 tag-dkw\" >\n\n        \n            <div class=\"inner-wrap post-458253 post type-post status-publish format-standard has-post-thumbnail category-638 tag-dkw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/dkw-f11-de-luxe-1965\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2040-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/dkw-f11-de-luxe-1965\/\" ><span class=\"screen-reader-text\">DKW F11 De Luxe 1965<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">DKW F11 De Luxe 1965<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-63 | \u20ac 10,000-12,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458253\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458255 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jeep\" >\n\n        \n            <div class=\"inner-wrap post-458255 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jeep\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jeep-wrangler-tj-2006\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2054-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jeep-wrangler-tj-2006\/\" ><span class=\"screen-reader-text\">Jeep Wrangler TJ 2006<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jeep Wrangler TJ 2006<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-64 | \u20ac16,000-18,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458255\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458257 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458257 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-300se-1990\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2097-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-300se-1990\/\" ><span class=\"screen-reader-text\">Mercedes Benz 300SE 1990<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 300SE 1990<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-65 | \u20ac10,500-12,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458257\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458259 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458259 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-s600-lorinser-bi-turbo-5-5l-v12-rwd-2006\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2085-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-s600-lorinser-bi-turbo-5-5l-v12-rwd-2006\/\" ><span class=\"screen-reader-text\">Mercedes-Benz S600 Lorinser Bi-Turbo 5.5L V12 RWD 2006<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes-Benz S600 Lorinser Bi-Turbo 5.5L V12 RWD 2006<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-66 | \u20ac 19,500-22,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458259\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458261 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458261 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-230-e-w123-1984-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2003-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-230-e-w123-1984-2\/\" ><span class=\"screen-reader-text\">Mercedes-Benz 230E W123 1984<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes-Benz 230E W123 1984<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-67 | \u20ac 9,500-11,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458261\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458263 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458263 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-200-t-w123-combi-1982\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2086-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-200-t-w123-combi-1982\/\" ><span class=\"screen-reader-text\">Mercedes-Benz 200 T (W123) Estate 1982<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes-Benz 200 T (W123) Estate 1982<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-68 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458263\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458265 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\" >\n\n        \n            <div class=\"inner-wrap post-458265 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-944-3-0-s2-coupe-1991\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2077-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-944-3-0-s2-coupe-1991\/\" ><span class=\"screen-reader-text\">Porsche 944 3.0 S2 Coupe 1991<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Porsche 944 3.0 S2 Coupe 1991<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-69 | \u20ac15,000-17,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458265\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458267 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\" >\n\n        \n            <div class=\"inner-wrap post-458267 post type-post status-publish format-standard has-post-thumbnail category-638 tag-porsche\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-cayenne-3-0-s-hybrid-2010\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2075-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/porsche-cayenne-3-0-s-hybrid-2010\/\" ><span class=\"screen-reader-text\">Porsche Cayenne 3.0 S Hybrid 2010<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Porsche Cayenne 3.0 S Hybrid 2010<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-70 | \u20ac 29,500-32,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458267\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458269 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\" >\n\n        \n            <div class=\"inner-wrap post-458269 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-silver-shadow-ii-1980\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2071-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-silver-shadow-ii-1980\/\" ><span class=\"screen-reader-text\">Rolls Royce Silver Shadow II 1980<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Rolls Royce Silver Shadow II 1980<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-80 | \u20ac16,500-18,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458269\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458271 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458271 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-mustang-gt-5-0-v8-2015\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2050-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-mustang-gt-5-0-v8-2015\/\" ><span class=\"screen-reader-text\">Ford Mustang GT 5.0 V8 2015<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford Mustang GT 5.0 V8 2015<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-81 | \u20ac 37,000-44,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458271\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458273 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458273 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-explorer-v8-xlt-eddy-bauer-4-6l-4wd-2007-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1923-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-explorer-v8-xlt-eddy-bauer-4-6l-4wd-2007-3\/\" ><span class=\"screen-reader-text\">Ford Explorer V8 XLT Eddy Bauer 4.6L 4WD 2007<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford Explorer V8 XLT Eddy Bauer 4.6L 4WD 2007<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-82 | \u20ac14,500-16,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458273\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458275 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458275 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-550i-touring-panorama-2007-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1983-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-550i-touring-panorama-2007-2\/\" ><span class=\"screen-reader-text\">BMW 550i Touring Panorama 2007<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW 550i Touring Panorama 2007<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-83 | \u20ac 22,000-26,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458275\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458277 post type-post status-publish format-standard has-post-thumbnail category-638 tag-auto-union\" >\n\n        \n            <div class=\"inner-wrap post-458277 post type-post status-publish format-standard has-post-thumbnail category-638 tag-auto-union\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/auto-union-1000s-1963\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2045-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/auto-union-1000s-1963\/\" ><span class=\"screen-reader-text\">Auto Union 1000S 1963<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Auto Union 1000S 1963<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-84 | \u20ac7,500-8,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458277\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458279 post type-post status-publish format-standard has-post-thumbnail category-638 tag-audi\" >\n\n        \n            <div class=\"inner-wrap post-458279 post type-post status-publish format-standard has-post-thumbnail category-638 tag-audi\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/audi-a8-3-0-v6-tdi-quattro-2009-6\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/A-2020-702-2-2.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/audi-a8-3-0-v6-tdi-quattro-2009-6\/\" ><span class=\"screen-reader-text\">Audi A8 3.0 V6 TDI Quattro 2009<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Audi A8 3.0 V6 TDI Quattro 2009<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-85 | \u20ac 14,000-16,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458279\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458281 post type-post status-publish format-standard has-post-thumbnail category-638 tag-alfa-romeo\" >\n\n        \n            <div class=\"inner-wrap post-458281 post type-post status-publish format-standard has-post-thumbnail category-638 tag-alfa-romeo\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/alfa-romeo-spider-1992\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2055-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/alfa-romeo-spider-1992\/\" ><span class=\"screen-reader-text\">Alfa Romeo Spider 1992<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Alfa Romeo Spider 1992<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-86 | \u20ac17,000-19,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458281\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458283 post type-post status-publish format-standard has-post-thumbnail category-638 tag-maserati\" >\n\n        \n            <div class=\"inner-wrap post-458283 post type-post status-publish format-standard has-post-thumbnail category-638 tag-maserati\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/maserati-biturbo-425-1991\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2063-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/maserati-biturbo-425-1991\/\" ><span class=\"screen-reader-text\">Maserati Biturbo 425 1991<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Maserati Biturbo 425 1991<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-87 | \u20ac 14,000-16,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458283\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458285 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458285 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-explorer-v6-xlt-4-0l-2010-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1999-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-explorer-v6-xlt-4-0l-2010-2\/\" ><span class=\"screen-reader-text\">Ford Explorer V6 XLT 4.0L 2010<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford Explorer V6 XLT 4.0L 2010<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-88 | \u20ac15,500-18,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458285\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458287 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\" >\n\n        \n            <div class=\"inner-wrap post-458287 post type-post status-publish format-standard has-post-thumbnail category-638 tag-rolls-royce\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-silver-wraith-ii-6-8-1980-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1954-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/rolls-royce-silver-wraith-ii-6-8-1980-3\/\" ><span class=\"screen-reader-text\">Rolls Royce Silver Wraith II 6.8 1980<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Rolls Royce Silver Wraith II 6.8 1980<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-89 | \u20ac 9,500-11,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458287\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458289 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458289 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-mustang-v8-coupe-1970-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2000-2-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-mustang-v8-coupe-1970-2\/\" ><span class=\"screen-reader-text\">Ford Mustang V8 Coupe 1970<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford Mustang V8 Coupe 1970<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-90 | \u20ac 24,000-27,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458289\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458291 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458291 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-190e-2-6-evo2-look-1990-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1947-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-190e-2-6-evo2-look-1990-3\/\" ><span class=\"screen-reader-text\">Mercedes-Benz 190E 2.6 EVO2 Look 1990<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes-Benz 190E 2.6 EVO2 Look 1990<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-91 | \u20ac 45,000-49,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458291\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458293 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458293 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-380-sel-1984\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2091-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-380-sel-1984\/\" ><span class=\"screen-reader-text\">Mercedes Benz 380 SEL 1984<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 380 SEL 1984<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-92 | \u20ac7,000-8,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458293\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458295 post type-post status-publish format-standard has-post-thumbnail category-638 tag-morris\" >\n\n        \n            <div class=\"inner-wrap post-458295 post type-post status-publish format-standard has-post-thumbnail category-638 tag-morris\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/morris-minor-1000-custom-trailer-1965\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2081-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/morris-minor-1000-custom-trailer-1965\/\" ><span class=\"screen-reader-text\">Morris Minor 1000 Custom Trailer 1965<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Morris Minor 1000 Custom Trailer 1965<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-93 | \u20ac 14,500-16,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458295\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458297 post type-post status-publish format-standard has-post-thumbnail category-638 tag-lancia\" >\n\n        \n            <div class=\"inner-wrap post-458297 post type-post status-publish format-standard has-post-thumbnail category-638 tag-lancia\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/lancia-fulvia-coupe-1-3-s-1972\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2062-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/lancia-fulvia-coupe-1-3-s-1972\/\" ><span class=\"screen-reader-text\">Lancia Fulvia Coup\u00e9 1.3 S 1972<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Lancia Fulvia Coup\u00e9 1.3 S 1972<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-94 | \u20ac14,500-16,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458297\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458299 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458299 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-750ld-xdrive-executive-2014-4\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1790-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-750ld-xdrive-executive-2014-4\/\" ><span class=\"screen-reader-text\">BMW 750Ld xDrive Executive 2014<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW 750Ld xDrive Executive 2014<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-95 | \u20ac 19,500-22,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458299\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458301 post type-post status-publish format-standard has-post-thumbnail category-638 tag-chrysler\" >\n\n        \n            <div class=\"inner-wrap post-458301 post type-post status-publish format-standard has-post-thumbnail category-638 tag-chrysler\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/chrysler-300c-srt8-touring-2007\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2108-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/chrysler-300c-srt8-touring-2007\/\" ><span class=\"screen-reader-text\">Chrysler 300C SRT8 Touring 2007<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Chrysler 300C SRT8 Touring 2007<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-96 | \u20ac 11,500-14,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458301\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458303 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458303 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-sl-500-2005-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1986-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-sl-500-2005-2\/\" ><span class=\"screen-reader-text\">Mercedes Benz SL 500 2005<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz SL 500 2005<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-97 | \u20ac 23,000-26,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458303\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458305 post type-post status-publish format-standard has-post-thumbnail category-638 tag-pontiac\" >\n\n        \n            <div class=\"inner-wrap post-458305 post type-post status-publish format-standard has-post-thumbnail category-638 tag-pontiac\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/pontiac-firebird-6-5-fw-87-formula-1977\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2079-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/pontiac-firebird-6-5-fw-87-formula-1977\/\" ><span class=\"screen-reader-text\">Pontiac Firebird 6.5 FW 87 Formula 1977<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Pontiac Firebird 6.5 FW 87 Formula 1977<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-98 | \u20ac 19,500-22,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458305\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458307 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\" >\n\n        \n            <div class=\"inner-wrap post-458307 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-joker-t3-td-kampeerauto-1987\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2064-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-joker-t3-td-kampeerauto-1987\/\" ><span class=\"screen-reader-text\">Volkswagen Joker T3 TD Campervan 1987<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volkswagen Joker T3 TD Campervan 1987<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-99 | \u20ac 19,500-22,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458307\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458309 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458309 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-260-e-1986\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2092-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-260-e-1986\/\" ><span class=\"screen-reader-text\">Mercedes Benz 260 E 1986<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 260 E 1986<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-100 | \u20ac7,500-8,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458309\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458311 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458311 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-230-te-w124-combi-1986\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2084-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-230-te-w124-combi-1986\/\" ><span class=\"screen-reader-text\">Mercedes-Benz 230 TE (W124) Estate 1986<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes-Benz 230 TE (W124) Estate 1986<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-101 | \u20ac 5,900-6,900 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458311\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458313 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\" >\n\n        \n            <div class=\"inner-wrap post-458313 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xj8-4-2-v8-2006\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1961-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xj8-4-2-v8-2006\/\" ><span class=\"screen-reader-text\">Jaguar XJ8 4.2 V8 2006<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jaguar XJ8 4.2 V8 2006<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-102| \u20ac 11,000-13,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458313\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458315 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\" >\n\n        \n            <div class=\"inner-wrap post-458315 post type-post status-publish format-standard has-post-thumbnail category-638 tag-ford\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-transit-nugget-euroline-2005-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2080-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/ford-transit-nugget-euroline-2005-2\/\" ><span class=\"screen-reader-text\">Ford Transit Nugget Euroline 2005<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Ford Transit Nugget Euroline 2005<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-103| \u20ac 6,500-7,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458315\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458317 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\" >\n\n        \n            <div class=\"inner-wrap post-458317 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-130-berlina-1970-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1962-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-130-berlina-1970-2\/\" ><span class=\"screen-reader-text\">Fiat 130 Berlina 1970<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Fiat 130 Berlina 1970<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-104| \u20ac8,500-9,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458317\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458319 post type-post status-publish format-standard has-post-thumbnail category-638 tag-chevrolet\" >\n\n        \n            <div class=\"inner-wrap post-458319 post type-post status-publish format-standard has-post-thumbnail category-638 tag-chevrolet\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/chevrolet-corvette-c4-1994-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1992-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/chevrolet-corvette-c4-1994-2\/\" ><span class=\"screen-reader-text\">Chevrolet Corvette C4 1994<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Chevrolet Corvette C4 1994<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-105 | \u20ac 14,500-16,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458319\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458321 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458321 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-z3-roadster-1-9-1997-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1991-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-z3-roadster-1-9-1997-2\/\" ><span class=\"screen-reader-text\">BMW Z3 Roadster 1.9 1997<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW Z3 Roadster 1.9 1997<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-106| \u20ac8,500-9,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458321\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458323 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458323 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-3-serie-315-1983-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1989-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-3-serie-315-1983-2\/\" ><span class=\"screen-reader-text\">BMW 3-Series 315 1983<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW 3-Series 315 1983<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-107| \u20ac8,000-9,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458323\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458325 post type-post status-publish format-standard has-post-thumbnail category-638 tag-audi\" >\n\n        \n            <div class=\"inner-wrap post-458325 post type-post status-publish format-standard has-post-thumbnail category-638 tag-audi\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/audi-a6-2-0tfsi-s-line-2011\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2036-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/audi-a6-2-0tfsi-s-line-2011\/\" ><span class=\"screen-reader-text\">Audi A6 2.0TFSI S line 2011<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Audi A6 2.0TFSI S line 2011<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-108| \u20ac 9,500-11,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458325\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458327 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\" >\n\n        \n            <div class=\"inner-wrap post-458327 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-500-nuova-1968-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1997-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-500-nuova-1968-2\/\" ><span class=\"screen-reader-text\">Fiat 500 Nuova 1968<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Fiat 500 Nuova 1968<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-109 | \u20ac 9,500-11,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458327\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458329 post type-post status-publish format-standard has-post-thumbnail category-638 tag-honda\" >\n\n        \n            <div class=\"inner-wrap post-458329 post type-post status-publish format-standard has-post-thumbnail category-638 tag-honda\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/honda-civic-1-5-lsi-1992\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2051-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/honda-civic-1-5-lsi-1992\/\" ><span class=\"screen-reader-text\">Honda Civic 1.5LSi 1992<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Honda Civic 1.5LSi 1992<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-110 | \u20ac 3,900-4,800 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458329\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458331 post type-post status-publish format-standard has-post-thumbnail category-638 tag-land-rover\" >\n\n        \n            <div class=\"inner-wrap post-458331 post type-post status-publish format-standard has-post-thumbnail category-638 tag-land-rover\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/land-rover-range-rover-classic-3-5-v8-1981-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1913-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/land-rover-range-rover-classic-3-5-v8-1981-3\/\" ><span class=\"screen-reader-text\">Land Rover Range Rover Classic 3.5 V8 1981<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Land Rover Range Rover Classic 3.5 V8 1981<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-111 | \u20ac 43,000-48,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458331\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458333 post type-post status-publish format-standard has-post-thumbnail category-638 tag-land-rover\" >\n\n        \n            <div class=\"inner-wrap post-458333 post type-post status-publish format-standard has-post-thumbnail category-638 tag-land-rover\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/land-rover-range-rover-sport-4-2-v8-supercharged-2005-5\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1773-2-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/land-rover-range-rover-sport-4-2-v8-supercharged-2005-5\/\" ><span class=\"screen-reader-text\">Land Rover Range Rover Sport 4.2 V8 Supercharged 2005<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Land Rover Range Rover Sport 4.2 V8 Supercharged 2005<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-112| \u20ac 12,500-14,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458333\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458335 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458335 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-450-sl-1978-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1934-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-450-sl-1978-2\/\" ><span class=\"screen-reader-text\">Mercedes Benz 450 SL 1978<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 450 SL 1978<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-113| \u20ac 19,500-21,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458335\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458337 post type-post status-publish format-standard has-post-thumbnail category-638 tag-morris\" >\n\n        \n            <div class=\"inner-wrap post-458337 post type-post status-publish format-standard has-post-thumbnail category-638 tag-morris\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/morris-minor-1000-tourer-convertible-1967\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2082-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/morris-minor-1000-tourer-convertible-1967\/\" ><span class=\"screen-reader-text\">Morris Minor 1000 Tourer Convertible 1967<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Morris Minor 1000 Tourer Convertible 1967<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-114| \u20ac 11,500-13,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458337\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458339 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\" >\n\n        \n            <div class=\"inner-wrap post-458339 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-golf-1-8-gti-1991-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2005-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-golf-1-8-gti-1991-2\/\" ><span class=\"screen-reader-text\">Volkswagen Golf 1.8 GTI 1991<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volkswagen Golf 1.8 GTI 1991<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-115| \u20ac 9,800-11,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458339\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458341 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\" >\n\n        \n            <div class=\"inner-wrap post-458341 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xj-5-3-v12-coupe-1976-4\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1857-1-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xj-5-3-v12-coupe-1976-4\/\" ><span class=\"screen-reader-text\">Jaguar XJ 5.3 V12 Coupe 1976<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jaguar XJ 5.3 V12 Coupe 1976<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-116| \u20ac 24,000-29,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458341\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458343 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458343 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-318i-cabriolet-1996-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1971-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-318i-cabriolet-1996-2\/\" ><span class=\"screen-reader-text\">BMW 318i Convertible 1996<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW 318i Convertible 1996<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-117 | \u20ac8,500-9,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458343\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458345 post type-post status-publish format-standard has-post-thumbnail category-638 tag-cadillac\" >\n\n        \n            <div class=\"inner-wrap post-458345 post type-post status-publish format-standard has-post-thumbnail category-638 tag-cadillac\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/cadillac-eldorado-touring-coupe-4-6-v8-1998-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1950-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/cadillac-eldorado-touring-coupe-4-6-v8-1998-2\/\" ><span class=\"screen-reader-text\">Cadillac Eldorado Touring Coupe 4.6 V8 1998<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Cadillac Eldorado Touring Coupe 4.6 V8 1998<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-118| \u20ac10,500-12,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458345\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458347 post type-post status-publish format-standard has-post-thumbnail category-638 tag-daimler\" >\n\n        \n            <div class=\"inner-wrap post-458347 post type-post status-publish format-standard has-post-thumbnail category-638 tag-daimler\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/daimler-sovereign-1968\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2057-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/daimler-sovereign-1968\/\" ><span class=\"screen-reader-text\">Daimler Sovereign 1968<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Daimler Sovereign 1968<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-119 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458347\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458349 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volvo\" >\n\n        \n            <div class=\"inner-wrap post-458349 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volvo\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volvo-xc90-2-9-t6-exclusive-2003\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2100-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volvo-xc90-2-9-t6-exclusive-2003\/\" ><span class=\"screen-reader-text\">Volvo XC90 2.9 T6 Exclusive 2003<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volvo XC90 2.9 T6 Exclusive 2003<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-120| \u20ac8,000-9,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458349\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458351 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458351 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-280-ge-brabus-1984\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2109-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-280-ge-brabus-1984\/\" ><span class=\"screen-reader-text\">Mercedes Benz 280 GE Brabus 1984<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 280 GE Brabus 1984<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-121 | \u20ac 29,000-32,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458351\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458353 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\" >\n\n        \n            <div class=\"inner-wrap post-458353 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xjr-4-0-v8-1998\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2095-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xjr-4-0-v8-1998\/\" ><span class=\"screen-reader-text\">Jaguar XJR 4.0 V8 1998<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jaguar XJR 4.0 V8 1998<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-123| \u20ac 8,500-10,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458353\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458355 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458355 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-x5-3-0i-executive-2002-4\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1912-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-x5-3-0i-executive-2002-4\/\" ><span class=\"screen-reader-text\">BMW X5 3.0i Executive 2002<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW X5 3.0i Executive 2002<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-124 | \u20ac6,900-7,900 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458355\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458357 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458357 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-525i-2004-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1878-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-525i-2004-3\/\" ><span class=\"screen-reader-text\">BMW 525i 2004<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW 525i 2004<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-125 | \u20ac 4,900-5,800 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458357\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458359 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\" >\n\n        \n            <div class=\"inner-wrap post-458359 post type-post status-publish format-standard has-post-thumbnail category-638 tag-jaguar\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xj-5-3-v12-he-vandenplas-1985-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2001-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/jaguar-xj-5-3-v12-he-vandenplas-1985-2\/\" ><span class=\"screen-reader-text\">Jaguar XJ 5.3 V12 HE Vandenplas 1985<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Jaguar XJ 5.3 V12 HE Vandenplas 1985<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-126 | \u20ac 9,000-11,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458359\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458361 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\" >\n\n        \n            <div class=\"inner-wrap post-458361 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-133-1978-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1996-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-133-1978-2\/\" ><span class=\"screen-reader-text\">Fiat 133 1978<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Fiat 133 1978<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-127 | \u20ac 2,900-3,700 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458361\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458363 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458363 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-230-e-w123-1982\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2093-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-230-e-w123-1982\/\" ><span class=\"screen-reader-text\">Mercedes Benz 230 E (W123) 1982<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 230 E (W123) 1982<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-128| \u20ac 5,500-6,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458363\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458365 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458365 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-350-sl-2003-7\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2020-720-2-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-350-sl-2003-7\/\" ><span class=\"screen-reader-text\">Mercedes Benz 350 SL 2003<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 350 SL 2003<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-129 | \u20ac15,500-18,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458365\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458367 post type-post status-publish format-standard has-post-thumbnail category-638 tag-audi\" >\n\n        \n            <div class=\"inner-wrap post-458367 post type-post status-publish format-standard has-post-thumbnail category-638 tag-audi\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/audi-a6-4-2-v8-quattro-2007-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1963-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/audi-a6-4-2-v8-quattro-2007-2\/\" ><span class=\"screen-reader-text\">Audi A6 4.2 V8 Quattro 2007<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Audi A6 4.2 V8 Quattro 2007<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-130 | \u20ac8,000-9,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458367\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458369 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458369 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-125i-3-0i-lpg-g3-2008-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1903-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-125i-3-0i-lpg-g3-2008-3\/\" ><span class=\"screen-reader-text\">BMW 125i 3.0i LPG G3 2008<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW 125i 3.0i LPG G3 2008<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-131 | \u20ac 11,000-13,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458369\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458371 post type-post status-publish format-standard has-post-thumbnail category-638 tag-triumph\" >\n\n        \n            <div class=\"inner-wrap post-458371 post type-post status-publish format-standard has-post-thumbnail category-638 tag-triumph\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/triumph-2000-mk-ii-saloon-1972-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2103-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/triumph-2000-mk-ii-saloon-1972-2\/\" ><span class=\"screen-reader-text\">Triumph 2000 MK II Saloon 1972<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Triumph 2000 MK II Saloon 1972<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-132| \u20ac8,500-9,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458371\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458373 post type-post status-publish format-standard has-post-thumbnail category-638 tag-renault\" >\n\n        \n            <div class=\"inner-wrap post-458373 post type-post status-publish format-standard has-post-thumbnail category-638 tag-renault\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/renault-espace-1-6-dci-initiale-paris-7-persoons-2015\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2016-2-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/renault-espace-1-6-dci-initiale-paris-7-persoons-2015\/\" ><span class=\"screen-reader-text\">Renault Espace 1.6 dCi Initiale Paris 7-seater 2015<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Renault Espace 1.6 dCi Initiale Paris 7-seater 2015<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-133| \u20ac19,500-23,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458373\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458375 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\" >\n\n        \n            <div class=\"inner-wrap post-458375 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-golf-cabrio-1984\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1964-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-golf-cabrio-1984\/\" ><span class=\"screen-reader-text\">Volkswagen Golf Convertible 1984<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volkswagen Golf Convertible 1984<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-134 | \u20ac7,500-8,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458375\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458377 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458377 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-slk-200-kompressor-2000\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2088-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-slk-200-kompressor-2000\/\" ><span class=\"screen-reader-text\">Mercedes Benz SLK 200 Kompressor 2000<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz SLK 200 Kompressor 2000<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-135 | \u20ac 4,200-4,900 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458377\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458379 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\" >\n\n        \n            <div class=\"inner-wrap post-458379 post type-post status-publish format-standard has-post-thumbnail category-638 tag-bmw\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-320i-1982\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2056-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/bmw-320i-1982\/\" ><span class=\"screen-reader-text\">BMW 320i 1982<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">BMW 320i 1982<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-136 | \u20ac6,000-7,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458379\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458381 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458381 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-280e-1978\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2099-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-280e-1978\/\" ><span class=\"screen-reader-text\">Mercedes Benz 280E 1978<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 280E 1978<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-137 | \u20ac 4,200-4,900 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458381\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458383 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458383 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-450-slc-1978\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2098-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-450-slc-1978\/\" ><span class=\"screen-reader-text\">Mercedes Benz 450 SLC 1978<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 450 SLC 1978<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-139 | \u20ac 14,500-16,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458383\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458385 post type-post status-publish format-standard has-post-thumbnail category-638 tag-saab\" >\n\n        \n            <div class=\"inner-wrap post-458385 post type-post status-publish format-standard has-post-thumbnail category-638 tag-saab\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/saab-9-3-2-0t-s-business-edition-2001-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2008-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/saab-9-3-2-0t-s-business-edition-2001-2\/\" ><span class=\"screen-reader-text\">Saab 9-3 2.0t S Business Edition 2001<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Saab 9-3 2.0t S Business Edition 2001<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-140 | \u20ac 4,900-5,900 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458385\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458387 post type-post status-publish format-standard has-post-thumbnail category-638 tag-maserati\" >\n\n        \n            <div class=\"inner-wrap post-458387 post type-post status-publish format-standard has-post-thumbnail category-638 tag-maserati\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/maserati-quattroporte-4-9-v8-1983-4\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1782-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/maserati-quattroporte-4-9-v8-1983-4\/\" ><span class=\"screen-reader-text\">Maserati Quattroporte 4.9 V8 1983<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Maserati Quattroporte 4.9 V8 1983<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-141 | \u20ac 8,500-10,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458387\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458389 post type-post status-publish format-standard has-post-thumbnail category-638 tag-nsu\" >\n\n        \n            <div class=\"inner-wrap post-458389 post type-post status-publish format-standard has-post-thumbnail category-638 tag-nsu\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/nsu-wankel-spider-1967-3\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1966-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/nsu-wankel-spider-1967-3\/\" ><span class=\"screen-reader-text\">NSU Wankel Spider 1967<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">NSU Wankel Spider 1967<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-142| \u20ac 11,000-13,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458389\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458391 post type-post status-publish format-standard has-post-thumbnail category-638 tag-alfa-romeo\" >\n\n        \n            <div class=\"inner-wrap post-458391 post type-post status-publish format-standard has-post-thumbnail category-638 tag-alfa-romeo\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/alfa-romeo-spider-veloce-2-0l-1986-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1978-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/alfa-romeo-spider-veloce-2-0l-1986-2\/\" ><span class=\"screen-reader-text\">Alfa Romeo Spider Veloce 2.0L 1986<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Alfa Romeo Spider Veloce 2.0L 1986<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-143| \u20ac7,500-8,500 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458391\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458393 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\" >\n\n        \n            <div class=\"inner-wrap post-458393 post type-post status-publish format-standard has-post-thumbnail category-638 tag-fiat\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-127-special-900-1982\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2059-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/fiat-127-special-900-1982\/\" ><span class=\"screen-reader-text\">Fiat 127 Special 900 1982<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Fiat 127 Special 900 1982<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-144 | \u20ac 3,900-4,800 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458393\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458395 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\" >\n\n        \n            <div class=\"inner-wrap post-458395 post type-post status-publish format-standard has-post-thumbnail category-638 tag-volkswagen\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-transporter-california-coach-70xoa-1990\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2066-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/volkswagen-transporter-california-coach-70xoa-1990\/\" ><span class=\"screen-reader-text\">Volkswagen Transporter California Coach 70XOA 1990<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Volkswagen Transporter California Coach 70XOA 1990<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-145 | \u20ac 5,000-6,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458395\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458397 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458397 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-450-sel-1978-no-reserve\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2021-1651-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-450-sel-1978-no-reserve\/\" ><span class=\"screen-reader-text\">Mercedes-Benz 450 SEL 1978 \u2013 No Reserve<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes-Benz 450 SEL 1978 \u2013 No Reserve<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-146| NO reserve | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458397\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458399 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes\" >\n\n        \n            <div class=\"inner-wrap post-458399 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-380-sec-1983\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2060-7.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-380-sec-1983\/\" ><span class=\"screen-reader-text\">Mercedes 380 SEC 1983<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes 380 SEC 1983<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-147 | \u20ac 4,900-5,900 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458399\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458401 post type-post status-publish format-standard has-post-thumbnail category-638 tag-lancia\" >\n\n        \n            <div class=\"inner-wrap post-458401 post type-post status-publish format-standard has-post-thumbnail category-638 tag-lancia\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/lancia-beta-1600-1977-2\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-1967-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/lancia-beta-1600-1977-2\/\" ><span class=\"screen-reader-text\">Lancia Beta 1600 1977<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Lancia Beta 1600 1977<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-148 | \u20ac 3,000-4,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458401\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458403 post type-post status-publish format-standard has-post-thumbnail category-638 tag-daimler\" >\n\n        \n            <div class=\"inner-wrap post-458403 post type-post status-publish format-standard has-post-thumbnail category-638 tag-daimler\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/daimler-double-six-1995\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2106-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/daimler-double-six-1995\/\" ><span class=\"screen-reader-text\">Daimler Double Six 1995<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Daimler Double Six 1995<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-149 | \u20ac 3,900-4,900 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458403\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458405 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458405 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-280-sl-1985\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2104-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-280-sl-1985\/\" ><span class=\"screen-reader-text\">Mercedes Benz 280 SL 1985<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz 280 SL 1985<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-150 | \u20ac 22,000-24,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458405\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n      <div class=\"col span_4 post-458407 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\" >\n\n        \n            <div class=\"inner-wrap post-458407 post type-post status-publish format-standard has-post-thumbnail category-638 tag-mercedes-benz\">\n\n            <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-cls-55-amg-2001\/\"  class=\"img-link\"><span class=\"post-featured-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/archive.classiccar-auctions.com\/wp-content\/uploads\/2022\/12\/2022-2105-1.jpg\" class=\"attachment-portfolio-thumb size-portfolio-thumb wp-post-image\" alt=\"\" title=\"\" sizes=\"auto, (min-width: 1300px) 33vw, (min-width: 1000px) 33vw, (min-width: 690px) 100vw, 100vw\" \/><\/span><\/a><span class=\"meta-category\"><a class=\"67957\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/category\/67957\/\">67957<\/a><\/span><a class=\"entire-meta-link\" href=\"https:\/\/archive.classiccar-auctions.com\/en\/mercedes-benz-cls-55-amg-2001\/\" ><span class=\"screen-reader-text\">Mercedes Benz CLS 55 AMG 2001<\/span><\/a>\n            <div class=\"article-content-wrap\">\n              <div class=\"post-header\">\n                <span class=\"meta\"> December 14, 2022 <\/span>\n                <h3 class=\"title\">Mercedes Benz CLS 55 AMG 2001<\/h3>\n              <\/div><!--\/post-header-->\n              <div class=\"excerpt\">\n                67957-151 | \u20ac 12,500-15,000 | read more              <\/div>\n            <\/div>\n\n            <div class=\"post-meta\">\n              <span class=\"meta-author\"> <a href=\"https:\/\/archive.classiccar-auctions.com\/en\/author\/administrator\/\"> <i class=\"icon-default-style icon-salient-m-user\"><\/i> administrator<\/a> <\/span>\n\n              \n              <div class=\"nectar-love-wrap\">\n                <a href=\"#\" class=\"nectar-love\" id=\"nectar-love-458407\" title=\"love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a>              <\/div><!--\/nectar-love-wrap-->\n            <\/div>\n\n          <\/div>\n\n        \n      <\/div><!--\/col-->\n\n      \n    <\/div><!--\/blog-recent-->\n\n  \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Mercedes-Benz CLS 55 AMG 2001 Description Mercedes-Benz CLS 55 AMG 2001 Market Value: \u20ac 12,500-15,000 Date of first registration: 04-09-2001 Fuel: Petrol Registration: French documents Body: Coupe Transmission: Automatic Mileage reading.. ..","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-456277","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/archive.classiccar-auctions.com\/en\/wp-json\/wp\/v2\/pages\/456277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archive.classiccar-auctions.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/archive.classiccar-auctions.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/archive.classiccar-auctions.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archive.classiccar-auctions.com\/en\/wp-json\/wp\/v2\/comments?post=456277"}],"version-history":[{"count":4,"href":"https:\/\/archive.classiccar-auctions.com\/en\/wp-json\/wp\/v2\/pages\/456277\/revisions"}],"predecessor-version":[{"id":458641,"href":"https:\/\/archive.classiccar-auctions.com\/en\/wp-json\/wp\/v2\/pages\/456277\/revisions\/458641"}],"wp:attachment":[{"href":"https:\/\/archive.classiccar-auctions.com\/en\/wp-json\/wp\/v2\/media?parent=456277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}